{"id":1536,"date":"2019-06-05T12:49:03","date_gmt":"2019-06-05T12:49:03","guid":{"rendered":"https:\/\/hispaprint.com\/blog\/?p=1536"},"modified":"2025-05-28T07:48:58","modified_gmt":"2025-05-28T07:48:58","slug":"hacer-pedido-hispaprint-facil-rapido","status":"publish","type":"post","link":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/","title":{"rendered":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>\u00bfQuieres hacer tu primer pedido en Hispaprint? Es realmente f\u00e1cil, r\u00e1pido e intuitivo y en este post te damos las claves para que puedas realizarlo sin complicaciones ni p\u00e9rdidas de tiempo.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-color\" style=\"color:#000000\">Cuando entras en <a href=\"https:\/\/hispaprint.com\/\">Hispaprint.com<\/a> lo primero que te aparece es la home, en la que puedes ver todas las familias de productos y los materiales actualmente disponibles (materiales r\u00edgidos, papeles, vinilos, expositores, bastidores, directorios y accesorios). &nbsp;Todos los art\u00edculos son totalmente personalizables a excepci\u00f3n de los accesorios.<\/p>\n\n\n\n<p>En la parte derecha aparece el men\u00fa puedes ver las diferentes categor\u00edas de productos que ofrecemos, para que elijas seg\u00fan tus necesidades de forma r\u00e1pida.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-3-100-630x1024.jpg\" alt=\"\" class=\"wp-image-2429\" width=\"672\" height=\"1092\"\/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">1. <strong>Selecciona el material sobre el que desees imprimir<\/strong><\/h4>\n\n\n\n<p>Por ejemplo, vamos a seleccionar el <a href=\"https:\/\/hispaprint.com\/soportes-rigidos\/23-impresion-en-pvc.html\">Forex \u00a9 pvc<\/a> . Cuando seleccionas el soporte te aparece un cuadro de aviso en el que se plasman los requisitos b\u00e1sicos para la subida del archivo. Posteriormente, cierra este aviso.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-2-100.jpg\" alt=\"\" class=\"wp-image-2421\" width=\"494\" height=\"247\"\/><\/figure><\/div>\n\n\n\n<p>*<em>Dispones de plantillas y gu\u00edas de impresi\u00f3n descargables que te ofrecen la orientaci\u00f3n necesaria para la preparaci\u00f3n del archivo de forma correcta. Puedes encontrar estos documentos pdf en la parte derecha de la p\u00e1gina de cada material y en el apartado n\u00famero cuatro del proceso de compra.<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2. <strong>Empieza a configurar tu producto<\/strong><\/h4>\n\n\n\n<p>En el momento en que te sit\u00faas en la p\u00e1gina de un material, ver\u00e1s que aparecen fotos del soporte y en la parte izquierda est\u00e1 la descripci\u00f3n breve del mismo. Adem\u00e1s, bajo de la descripci\u00f3n tienes los botones para descargar las instrucciones y las plantillas. Seguidamente, aparece un cuadro a modo de calculadora en la que se va actualizando el presupuesto en base a las caracter\u00edsticas seleccionadas.<\/p>\n\n\n\n<p>Dentro del primer apartado del proceso de compra de producto debes de escoger&nbsp; diversas caracter\u00edsticas basadas en tus necesidades.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-5-100-1024x974.jpg\" alt=\"\" class=\"wp-image-2434\" width=\"543\" height=\"516\"\/><\/figure><\/div>\n\n\n\n<p>Primero selecciona el espesor o grosor del material. En este caso, podemos escoger entre cinco opciones. A continuaci\u00f3n, ver\u00e1s un cuadro azul en el que se indican las medidas m\u00e1ximas de impresi\u00f3n para una sola plancha. En el caso de que necesites una impresi\u00f3n de un tama\u00f1o superior, est\u00e1 se realizar\u00e1 de forma panelada.<\/p>\n\n\n\n<p>Luego escoge el formato del producto, con opci\u00f3n a personalizar las medidas de tu impresi\u00f3n o bien, puedes optar por uno de los formatos propuestos. Si eliges uno de los formatos est\u00e1ndar puedes descargarte la plantilla correspondiente para que la preparaci\u00f3n del archivo sea mucho m\u00e1s sencilla. Por el contrario, si se trata de una medida personalizada debes consultar las instrucciones que aparecen en el apartado cuatro o en la parte izquierda de la p\u00e1gina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-4-100-1-1024x401.jpg\" alt=\"\" class=\"wp-image-2454\"\/><\/figure>\n\n\n\n<p>M\u00e1s tarde, rellena el campo de cantidad (seg\u00fan el n\u00famero de productos iguales que necesites), elige el tipo de orientaci\u00f3n (horizontal o vertical) y &nbsp;las caracter\u00edsticas de impresi\u00f3n (a una cara que ser\u00eda s\u00f3lo anverso, o bien, a dos caras, con la opci\u00f3n de anverso y reverso iguales o diferentes). Tambi\u00e9n debes concretar el tipo de corte de tu impresi\u00f3n, si es recto o con forma, es decir, si se trata de un formato cuadrado de l\u00edneas rectas o si es una silueta con l\u00edneas curvas o formas especiales. <\/p>\n\n\n\n<p>El siguiente \u00edtem es marcar la calidad de impresi\u00f3n, de alta definici\u00f3n o de s\u00faper alta definici\u00f3n (HD o Super HD). Ahora s\u00f3lo debes subir el dise\u00f1o y asignarle un nombre al trabajo para facilitarnos su localizaci\u00f3n. <\/p>\n\n\n\n<p>El archivo de impresi\u00f3n tiene que estar preparado a escala 1:1 teniendo en cuenta las medidas que hayas configurado, a\u00f1adiendo 5mm. de sangrado por cada lado de la imagen y dando como resultado un cent\u00edmetro m\u00e1s tanto en ancho como en alto. Por lo tanto, si seleccionas el formato 35x35cm. el archivo de impresi\u00f3n deber\u00e1 tener 36x36cm.<\/p>\n\n\n\n<p>*<em>Esta regla del sangrado es aplicable a todos los soportes excepto a los bastidores y a los expositores que demandan un sangrado diferente. Puedes consultarlo en la gu\u00eda de impresi\u00f3n (situada en el foot de la web) y en las plantillas (cuarto paso de la configuraci\u00f3n del producto).<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3. Contacta con atenci\u00f3n al cliente de Hispaprint si necesitas ayuda<\/h4>\n\n\n\n<p>Si necesitas asesoramiento o consejo por parte de un profesional&nbsp; de la impresi\u00f3n para la confecci\u00f3n del archivo no dudes en contactar con el departamento de atenci\u00f3n al cliente de Hispaprint y te asesoraremos seg\u00fan tus necesidades.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4. <strong>Si quieres asegurarte de que tu impresi\u00f3n sea \u00f3ptima selecciona casilla \u201cS\u00ed\u201d en el apartado de servicios extra<\/strong><\/h4>\n\n\n\n<p>De este modo, el archivo de impresi\u00f3n que subas pasar\u00e1 un control minucioso por parte de un profesional de dise\u00f1o e impresi\u00f3n de Hispaprint que garantizar\u00e1 que el documento est\u00e9 preparado de la forma id\u00f3nea para producci\u00f3n.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-6-100-1024x543.jpg\" alt=\"\" class=\"wp-image-2456\" width=\"482\" height=\"255\"\/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">5. Resumen del presupuesto y a\u00f1adir al carrito<\/h4>\n\n\n\n<p>En el \u00faltimo apartado del proceso de compra podr\u00e1s ver un resumen del precio del material, con las caracter\u00edsticas de impresi\u00f3n y corte seleccionadas y con la fecha de entrega prevista. &nbsp;As\u00ed pues, si todo est\u00e1 configurado de forma correcta, puedes a\u00f1adir el producto al carrito. Aparecer\u00e1 un cuadro emergente con el resumen de la configuraci\u00f3n del producto y puedes continuar comprando otros art\u00edculos o bien pasar por caja.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-8-100-1024x598.jpg\" alt=\"\" class=\"wp-image-2467\"\/><\/figure>\n\n\n\n<p>*<em>Si necesitas imprimir varios dise\u00f1os o archivos sobre un mismo material deber\u00e1s realizar tantos procesos de compra como n\u00famero de dise\u00f1os diferentes precises imprimir.<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">6. A\u00f1adir otro producto diferente al carrito<\/h4>\n\n\n\n<p>Si deseas configurar otro producto antes de pasar por caja, simplemente pulsa el bot\u00f3n de continuar comprando y mu\u00e9vete por el men\u00fa lateral de la izquierda y pincha en la secci\u00f3n o categor\u00eda que te interese y podr\u00e1s seguir configurando art\u00edculos. Una vez hayas terminado con la configuraci\u00f3n de todos los productos pincha en el carrito y pasa por caja.<\/p>\n\n\n\n<p>Si tienes un c\u00f3digo de descuento promocional puedes a\u00f1adirlo en el paso final del carrito.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-7-100-1024x706.jpg\" alt=\"\" class=\"wp-image-2459\" width=\"574\" height=\"396\"\/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">7. Pasar por caja<\/h4>\n\n\n\n<p>Para pasar por caja te pedir\u00e1 que inicies sesi\u00f3n con tu cuenta de Hispaprint. Si todav\u00eda no tienes usuario rellena el formulario de nueva cuenta e introduce tus datos y por el contrario, si ya tienes la cuenta creada s\u00f3lo tienes que rellenar el campo de correo electr\u00f3nico y contrase\u00f1a.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-9-100-1024x571.jpg\" alt=\"\" class=\"wp-image-2468\" width=\"580\" height=\"323\"\/><\/figure><\/div>\n\n\n\n<p>Cuando vuelvas a pulsar en pasar por caja podr\u00e1s ver que el primer paso de <em>chekout<\/em> ya est\u00e1 rellenado con tus datos, los ya aportados en el formulario de registro de usuarios. El paso dos es la confirmaci\u00f3n de los datos de entrega, los cuales pueden ser modificados.<\/p>\n\n\n\n<p>A continuaci\u00f3n, debes escoger que topolog\u00eda de env\u00edo se adecua a tus necesidades, teniendo como opciones la recogida del pedido en la sede de Hispaprint y la entrega por parte de un transportista.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-10-100-1-1024x636.jpg\" alt=\"\" class=\"wp-image-2473\"\/><\/figure><\/div>\n\n\n\n<p>Por \u00faltimo, selecciona el m\u00e9todo de pago que desees, Paypal o tarjeta de cr\u00e9dito y acepta los t\u00e9rminos del servicio. Se te redigir\u00e1 al portal seguro donde puedes rellenar los datos de tu m\u00e9todo de pago y una vez pinches en pagar la orden del pedido habr\u00e1 llegado a Hispaprint y procederemos a producir los productos y a enviar el pedido en un plazo m\u00e1ximo de 72 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQuieres hacer tu primer pedido en Hispaprint? Es realmente f\u00e1cil, r\u00e1pido e intuitivo y en este post te damos las claves para que puedas realizarlo sin complicaciones ni p\u00e9rdidas de tiempo. Cuando entras en Hispaprint.com lo primero que te aparece es la home, en la que puedes ver todas las familias de productos y los materiales actualmente disponibles (materiales r\u00edgidos, papeles, vinilos,&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-1536","post","type-post","status-publish","format-standard","hentry","category-mundohispaprint"],"featured_image_src":null,"author_info":{"display_name":"","author_link":"https:\/\/hispaprint.com\/blog\/author\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido<\/title>\n<meta name=\"description\" content=\"Hacer un pedido en Hispaprint es muy sencillo. Sigue los pasos para pedir online tu impresi\u00f3n personalizada y rec\u00edbelo el d\u00eda que elijas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido\" \/>\n<meta property=\"og:description\" content=\"Hacer un pedido en Hispaprint es muy sencillo. Sigue los pasos para pedir online tu impresi\u00f3n personalizada y rec\u00edbelo el d\u00eda que elijas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Hispaprint.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hispaprint\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T12:49:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T07:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/HACER-UN-PEDIDO-EN-HISPAPRINT-ES-FACIL-Y-RAPIDO-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1669\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hispaprint\" \/>\n<meta name=\"twitter:site\" content=\"@hispaprint\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido","description":"Hacer un pedido en Hispaprint es muy sencillo. Sigue los pasos para pedir online tu impresi\u00f3n personalizada y rec\u00edbelo el d\u00eda que elijas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/","og_locale":"es_ES","og_type":"article","og_title":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido","og_description":"Hacer un pedido en Hispaprint es muy sencillo. Sigue los pasos para pedir online tu impresi\u00f3n personalizada y rec\u00edbelo el d\u00eda que elijas.","og_url":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/","og_site_name":"Blog de Hispaprint.com","article_publisher":"https:\/\/www.facebook.com\/hispaprint\/","article_published_time":"2019-06-05T12:49:03+00:00","article_modified_time":"2025-05-28T07:48:58+00:00","og_image":[{"width":1669,"height":901,"url":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/HACER-UN-PEDIDO-EN-HISPAPRINT-ES-FACIL-Y-RAPIDO-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@hispaprint","twitter_site":"@hispaprint","twitter_misc":{"Escrito por":"","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#article","isPartOf":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/"},"author":{"name":"","@id":""},"headline":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido","datePublished":"2019-06-05T12:49:03+00:00","dateModified":"2025-05-28T07:48:58+00:00","mainEntityOfPage":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/"},"wordCount":1258,"publisher":{"@id":"https:\/\/hispaprint.com\/blog\/#organization"},"image":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#primaryimage"},"thumbnailUrl":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-3-100-630x1024.jpg","articleSection":["Mundo Hispaprint"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/","url":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/","name":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido","isPartOf":{"@id":"https:\/\/hispaprint.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#primaryimage"},"image":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#primaryimage"},"thumbnailUrl":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-3-100-630x1024.jpg","datePublished":"2019-06-05T12:49:03+00:00","dateModified":"2025-05-28T07:48:58+00:00","description":"Hacer un pedido en Hispaprint es muy sencillo. Sigue los pasos para pedir online tu impresi\u00f3n personalizada y rec\u00edbelo el d\u00eda que elijas.","breadcrumb":{"@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#primaryimage","url":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-3-100-630x1024.jpg","contentUrl":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/Recurso-3-100-630x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hispaprint.com\/blog\/mundohispaprint\/hacer-pedido-hispaprint-facil-rapido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00b7 Blog","item":"https:\/\/hispaprint.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mundo Hispaprint","item":"https:\/\/hispaprint.com\/blog\/categoria\/mundohispaprint\/"},{"@type":"ListItem","position":3,"name":"Hacer un pedido en Hispaprint es f\u00e1cil y r\u00e1pido"}]},{"@type":"WebSite","@id":"https:\/\/hispaprint.com\/blog\/#website","url":"https:\/\/hispaprint.com\/blog\/","name":"Blog de Hispaprint.com","description":"","publisher":{"@id":"https:\/\/hispaprint.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hispaprint.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hispaprint.com\/blog\/#organization","name":"Hispaprint","url":"https:\/\/hispaprint.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hispaprint.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/LOGO-.jpg","contentUrl":"https:\/\/hispaprint.com\/blog\/wp-content\/uploads\/LOGO-.jpg","width":654,"height":167,"caption":"Hispaprint"},"image":{"@id":"https:\/\/hispaprint.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hispaprint\/","https:\/\/x.com\/hispaprint"]},{"@type":"Person","@id":"","url":"https:\/\/hispaprint.com\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":4,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"predecessor-version":[{"id":4021,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/posts\/1536\/revisions\/4021"}],"wp:attachment":[{"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hispaprint.com\/blog\/wp-json\/wp\/v2\/tags?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}